{"id":5411,"date":"2026-05-08T15:04:24","date_gmt":"2026-05-08T13:04:24","guid":{"rendered":"https:\/\/www.dallenogare.biz\/cours\/?p=5411"},"modified":"2026-05-13T11:44:15","modified_gmt":"2026-05-13T09:44:15","slug":"examen-de-juin-notions-et-auteurs-a-comprendre-et-integrer-dans-largumentation-ethique","status":"publish","type":"post","link":"https:\/\/www.dallenogare.biz\/cours\/examen-de-juin-notions-et-auteurs-a-comprendre-et-integrer-dans-largumentation-ethique\/","title":{"rendered":"Examen de juin de rh\u00e9to : notions et auteurs \u00e0 conna\u00eetre et comprendre pour les int\u00e9grer dans l\u2019argumentation \u00e9thique"},"content":{"rendered":"<p>L&rsquo;examen consistera en une argumentation \u00e9thique (sous forme de dialogue philosophique envisageant plusieurs r\u00e9ponses possibles &#8211; ou sous forme d&rsquo;une dissertation envisageant plusieurs r\u00e9ponses possibles).<\/p>\n<p>Une s\u00e9rie de sujets seront propos\u00e9s qui concerneront des probl\u00e8mes politiques, sociaux : l&rsquo;\u00e9l\u00e8ve en choisira un et d\u00e9veloppera plusieurs points de vue politiques possibles (au moins trois) permettant d&rsquo;agir face \u00e0 ce \u00ab\u00a0probl\u00e8me\u00a0\u00bb.<\/p>\n<p>Il faudra veiller \u00e0 bien entrer en profondeur dans la logique et les arguments de chacun des points de vues.<\/p>\n<p>L&rsquo;utilisation de tels ou tels des notions ou auteurs ci-dessous pourra \u00eatre impos\u00e9e selon les sujets :<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li><a href=\"https:\/\/www.dallenogare.biz\/cours\/le-hasard-et-la-necessite-quelques-citations-de-jacques-monod\/\" target=\"_blank\" rel=\"noopener\">Mat\u00e9rialisme<\/a><\/li>\n<li><a href=\"https:\/\/www.dallenogare.biz\/cours\/les-deux-recits-de-la-creation-de-letre-humain-dans-le-premier-livre-de-la-bible-suivis-des-commentaires-de-rachi\/\" target=\"_blank\" rel=\"noopener\">Spiritualisme<\/a><\/li>\n<li><a href=\"https:\/\/www.dallenogare.biz\/cours\/le-hasard-et-la-necessite-quelques-citations-de-jacques-monod\/\" target=\"_blank\" rel=\"noopener\">Hasard et n\u00e9cessit\u00e9 (Jacques Monod)<\/a><\/li>\n<li><a href=\"https:\/\/www.dallenogare.biz\/cours\/le-hasard-et-la-necessite-quelques-citations-de-jacques-monod\/\" target=\"_blank\" rel=\"noopener\">Cr\u00e9ation \/ cr\u00e9ationisme<\/a><\/li>\n<li><a href=\"https:\/\/www.dallenogare.biz\/cours\/le-hasard-et-la-necessite-quelques-citations-de-jacques-monod\/\" target=\"_blank\" rel=\"noopener\">Dessein intelligent<\/a><\/li>\n<li><a href=\"https:\/\/www.dallenogare.biz\/cours\/la-dynamique-de-la-creation-selon-pierre-teilhard-de-chardin\/\" target=\"_blank\" rel=\"noopener\">Noogen\u00e8se \/ pneumatogen\u00e8se (Teilhard de Chardin)<\/a><\/li>\n<li><a href=\"https:\/\/www.dallenogare.biz\/cours\/sengager-politiquement-des-reperes\/\" target=\"_blank\" rel=\"noopener\">Axes politiques de tension<\/a><\/li>\n<li><a href=\"https:\/\/www.dallenogare.biz\/cours\/allons-nous-vers-la-catastrophe-discerner-avec-alexandre-grothendieck\/\" target=\"_blank\" rel=\"noopener\">Catastrophisme \u00e9clair\u00e9 (Jean-Pierre Dupuy)<\/a><\/li>\n<li><a href=\"https:\/\/www.dallenogare.biz\/cours\/allons-nous-vers-la-catastrophe-discerner-avec-alexandre-grothendieck\/\" target=\"_blank\" rel=\"noopener\">Hans Jonas<\/a><\/li>\n<li><a href=\"https:\/\/www.dallenogare.biz\/cours\/tragique-antique-et-optimisme-biblique\/\" target=\"_blank\" rel=\"noopener\">Gnosticisme<\/a><\/li>\n<li>Transhumanisme<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<hr \/>\n<p><strong><a href=\"http:\/\/www.dallenogare.biz\/cours\/wp-content\/uploads\/2026\/05\/202505-examen-religion-rheto.docx.pdf\" target=\"_blank\" rel=\"noopener\">Afficher et t\u00e9l\u00e9charger le pdf de l&rsquo;article<\/a><\/strong><br \/>\n<a href=\"http:\/\/www.dallenogare.biz\/cours\/wp-content\/uploads\/2026\/05\/202505-examen-religion-rheto.docx\">Version texte .docx<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;examen consistera en une argumentation \u00e9thique (sous forme de dialogue philosophique envisageant plusieurs r\u00e9ponses possibles &#8211; ou sous forme d&rsquo;une &hellip; <a class=\"more-link\" href=\"https:\/\/www.dallenogare.biz\/cours\/examen-de-juin-notions-et-auteurs-a-comprendre-et-integrer-dans-largumentation-ethique\/\">Plus<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4,12,16,8],"tags":[],"class_list":["post-5411","post","type-post","status-publish","format-standard","hentry","category-documents-de-base","category-education-a-la-philosophie-et-citoyennete","category-libre-pour-me-decider-et-mengager","category-notions-fondamentales",""],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.dallenogare.biz\/cours\/wp-json\/wp\/v2\/posts\/5411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dallenogare.biz\/cours\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dallenogare.biz\/cours\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dallenogare.biz\/cours\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dallenogare.biz\/cours\/wp-json\/wp\/v2\/comments?post=5411"}],"version-history":[{"count":8,"href":"https:\/\/www.dallenogare.biz\/cours\/wp-json\/wp\/v2\/posts\/5411\/revisions"}],"predecessor-version":[{"id":5425,"href":"https:\/\/www.dallenogare.biz\/cours\/wp-json\/wp\/v2\/posts\/5411\/revisions\/5425"}],"wp:attachment":[{"href":"https:\/\/www.dallenogare.biz\/cours\/wp-json\/wp\/v2\/media?parent=5411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dallenogare.biz\/cours\/wp-json\/wp\/v2\/categories?post=5411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dallenogare.biz\/cours\/wp-json\/wp\/v2\/tags?post=5411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}